{"id":1467,"date":"2023-07-20T17:35:58","date_gmt":"2023-07-20T20:35:58","guid":{"rendered":"https:\/\/www.yampi.com.br\/blog\/?p=1467"},"modified":"2025-08-11T16:09:43","modified_gmt":"2025-08-11T19:09:43","slug":"ltv-lifetime-value","status":"publish","type":"post","link":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/","title":{"rendered":"Como aumentar o LTV da sua loja virtual em 7 estrat\u00e9gias"},"content":{"rendered":"\n<p>Se voc\u00ea possui um e-commerce, com certeza j\u00e1 ouviu falar sobre o <strong>LTV<\/strong>.&nbsp;<\/p>\n\n\n\n<p>A sigla representa a express\u00e3o <strong><em>lifetime value<\/em><\/strong>, ou valor vital\u00edcio pelo tempo de relacionamento entre o seu neg\u00f3cio e cliente.&nbsp;<\/p>\n\n\n\n<p>Portanto, vamos entender tudo sobre essa m\u00e9trica e como calcular o LTV, al\u00e9m de aprender estrat\u00e9gias que v\u00e3o fazer a diferen\u00e7a na sua loja virtual!<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_73 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#Qual_o_significado_de_LTV_ou_lifetime_value\" title=\"Qual o significado de LTV, ou lifetime value?\">Qual o significado de LTV, ou lifetime value?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#E_por_que_e_importante_calcular_o_LTV_de_uma_loja_virtual\" title=\"E por que \u00e9 importante calcular o LTV de uma loja virtual?\">E por que \u00e9 importante calcular o LTV de uma loja virtual?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#6_metricas_necessarias_para_calcular_o_LTV\" title=\"6 m\u00e9tricas necess\u00e1rias para calcular o LTV\">6 m\u00e9tricas necess\u00e1rias para calcular o LTV<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#Como_calcular_o_LTV_passo_a_passo\" title=\"Como calcular o LTV passo a passo\">Como calcular o LTV passo a passo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#Dicas_para_analisar_o_LTV_do_seu_e-commerce\" title=\"Dicas para analisar o LTV do seu e-commerce\">Dicas para analisar o LTV do seu e-commerce<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#O_que_se_considera_um_bom_lifetime_value_no_e-commerce\" title=\"O que se considera um bom lifetime value no e-commerce?\">O que se considera um bom lifetime value no e-commerce?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#Como_aumentar_o_LTV_da_minha_loja_virtual\" title=\"Como aumentar o LTV da minha loja virtual?\">Como aumentar o LTV da minha loja virtual?<\/a><\/li><\/ul><\/nav><\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Qual_o_significado_de_LTV_ou_lifetime_value\"><\/span>Qual o significado de LTV, ou <em>lifetime value<\/em>?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O <strong>LTV <\/strong>\u00e9 uma sigla que significa <em>lifetime value<\/em>. Em outras palavras, \u00e9 um indicador que calcula o valor vital\u00edcio ou o valor que um cliente vai gastar com a sua <a href=\"https:\/\/www.yampi.com.br\/blog\/loja-virtual\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\">loja virtual<\/a> durante o per\u00edodo que se relaciona com ela.&nbsp;<\/p>\n\n\n\n<p>O conceito de LTV \u00e9 muito utilizado em <strong>marketing <\/strong>e na an\u00e1lise de neg\u00f3cios e est\u00e1 ligado essencialmente \u00e0 lucratividade de uma empresa.<\/p>\n\n\n\n<p>Consequentemente, o LTV tamb\u00e9m representa o <strong>quanto um neg\u00f3cio pode perder<\/strong> caso esse cliente decida n\u00e3o consumir mais os produtos ou servi\u00e7os.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"E_por_que_e_importante_calcular_o_LTV_de_uma_loja_virtual\"><\/span>E por que \u00e9 importante calcular o LTV de uma loja virtual?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Se voc\u00ea ainda tem d\u00favidas de que calcular o LTV \u00e9 fundamental para a sa\u00fade financeira do seu e-commerce, d\u00e1 uma olhada nesses n\u00fameros da <a href=\"https:\/\/datareportal.com\/reports\/digital-2023-global-overview-report\" target=\"_blank\" rel=\"noreferrer noopener\">Global Overview Report<\/a>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Em janeiro de 2023, foram contabilizados mais de <strong>5.15 bilh\u00f5es<\/strong> de usu\u00e1rios de internet;<\/li>\n\n\n\n<li>Desses, <strong>43,4% da popula\u00e7\u00e3o utiliza para procurar por produtos e marcas<\/strong>;<\/li>\n\n\n\n<li><strong>76%<\/strong> dos sites mais visitados no mundo s\u00e3o de <strong>compras<\/strong>;<\/li>\n\n\n\n<li><strong>29,3%<\/strong> das pessoas afirma realizar <strong>alguma compra online semanalmente<\/strong>.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>O que isso significa?<\/p>\n\n\n\n<p>Que as pessoas est\u00e3o cada vez mais presentes no ambiente online, e que os <strong>h\u00e1bitos de consumo <\/strong>e de compra seguem em crescimento no com\u00e9rcio eletr\u00f4nico.<\/p>\n\n\n\n<p>Nesse contexto, o LTV representa tamb\u00e9m a <strong>fidelidade <\/strong>dos clientes junto ao seu neg\u00f3cio. O valor agregado atrelado \u00e0 <strong>experi\u00eancia de compra <\/strong>faz com que essas pessoas voltem \u00e0 sua loja virtual.&nbsp;<\/p>\n\n\n\n<p>Com <a href=\"https:\/\/www.yampi.com.br\/blog\/cliente-recorrente\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\">clientes recorrentes<\/a> e valiosos, sua empresa garante a sustentabilidade do neg\u00f3cio a m\u00e9dio e longo prazo, entendendo o custo de aquisi\u00e7\u00e3o e o valor monet\u00e1rio que resulta dessa rela\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Vamos entender melhor as <a href=\"https:\/\/www.yampi.com.br\/blog\/metricas-do-e-commerce\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\">m\u00e9tricas importantes<\/a> para calcular o LTV no pr\u00f3ximo item.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_metricas_necessarias_para_calcular_o_LTV\"><\/span>6 m\u00e9tricas necess\u00e1rias para calcular o LTV<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para calcular o LTV, \u00e9 preciso entender algumas m\u00e9tricas relevantes para o seu neg\u00f3cio &#8211; e que impactam diretamente no <em>lifetime value<\/em>.&nbsp;<\/p>\n\n\n\n<p>Separamos 6 m\u00e9tricas valiosas e necess\u00e1rias no processo:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.yampi.com.br\/blog\/taxa-de-conversao-e-commerce\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Taxa de convers\u00e3o<\/strong><\/a>: representa quantas pessoas de fato conclu\u00edram uma compra no seu e-commerce, em compara\u00e7\u00e3o com a quantidade de visitantes;<\/li>\n\n\n\n<li><strong>Ticket m\u00e9dio<\/strong>: representa o valor m\u00e9dio de cada&nbsp; venda do seu site em determinado per\u00edodo;<\/li>\n\n\n\n<li><strong>Custo por Aquisi\u00e7\u00e3o de Cliente<\/strong>: tamb\u00e9m conhecido como CAC, \u00e9 o valor investido para adquirir novos clientes em an\u00fancios, descontos, campanhas de m\u00eddia nas redes sociais;<\/li>\n\n\n\n<li><strong>ROI<\/strong>: similar ao CAC, mas voltado para um canal espec\u00edfico, \u00e9 a taxa que mostra quanto do valor alocado em uma m\u00eddia ou canal gerou de resultado (que pode ser convers\u00e3o, cliques, visitas);<\/li>\n\n\n\n<li><strong>Taxa de churn<\/strong>: representa a m\u00e9dia de clientes que deixaram de comprar na sua loja em um determinado per\u00edodo de tempo;<\/li>\n\n\n\n<li><strong>Taxa de recompra e reten\u00e7\u00e3o<\/strong>: representa quantas vezes um mesmo cliente realiza compras na sua loja virtual, dentro de um per\u00edodo de tempo espec\u00edfico.&nbsp;<\/li>\n<\/ol>\n\n\n\n<p>Agora que voc\u00ea j\u00e1 sabe em quais m\u00e9tricas deve ficar de olho, vamos aprender a usar esses valores para calcular o LTV da sua loja virtual.&nbsp;<\/p>\n\n\n\n<div data-formulario-artigo role=\"main\" id=\"blog-planilha-de-kpis-200aa83e2e49a837f96c\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_calcular_o_LTV_passo_a_passo\"><\/span>Como calcular o LTV passo a passo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O c\u00e1lculo do LTV depende da coleta e armazenamento de alguns dados importantes para o contexto da sua loja.&nbsp;<\/p>\n\n\n\n<p>Vamos entender a f\u00f3rmula:<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>LTV = (ticket m\u00e9dio x m\u00e9dia de compras do cliente por ano) x m\u00e9dia de tempo de relacionamento do cliente com o e-commerce<\/strong><\/p>\n\n\n\n<p>Vamos a um exemplo pr\u00e1tico?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Digamos que a sua loja virtual tem um cliente que compra h\u00e1 2 anos;<\/li>\n\n\n\n<li>Em m\u00e9dia, esse cliente faz 5 compras por ano;<\/li>\n\n\n\n<li>Nesse per\u00edodo, o ticket m\u00e9dio das compras desse cliente \u00e9 de R$ 2.000 reais.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>O c\u00e1lculo fica assim:<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>LTV = (2000 x 5) x 2 = R$20.000.<\/strong><\/p>\n\n\n\n<p>Viu como \u00e9 simples?<\/p>\n\n\n\n<p>Esse valor monet\u00e1rio representa <strong>o quanto o seu cliente recorrente vale para a sua loja virtual durante todo o tempo de relacionamento<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Em outras palavras, se esse cliente deixar de comprar de voc\u00ea, em um per\u00edodo de 2 anos sua loja ter\u00e1 uma perda, em m\u00e9dia, de R$20.000.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Dicas_para_analisar_o_LTV_do_seu_e-commerce\"><\/span>Dicas para analisar o LTV do seu e-commerce<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A an\u00e1lise do LTV pode trazer <strong>novas ideias<\/strong> para os gestores de como seguir e melhorar as <a href=\"https:\/\/www.yampi.com.br\/blog\/como-fazer-vendas-online-dicas-de-produtos-plataformas-e-muito-mais\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\">vendas online<\/a> do e-commerce.&nbsp;<\/p>\n\n\n\n<p>Quando voc\u00ea entende quanto custa o <strong>relacionamento <\/strong>e o <strong>valor vital\u00edcio <\/strong>do seu cliente, fica mais f\u00e1cil perceber e projetar o aumento de receita ao longo do tempo, o que impacta na sa\u00fade financeira do seu neg\u00f3cio.<\/p>\n\n\n\n<p>Mas vale lembrar que o LTV deve ser monitorado juntamente com o<strong> custo de aquisi\u00e7\u00e3o<\/strong> e investimento em estrat\u00e9gias de marketing para atrair ou fidelizar os clientes. Assim, \u00e9 poss\u00edvel relacionar o LTV com o CAC para entender o custo efetivo e o resultado em retorno de venda.<\/p>\n\n\n\n<p>Al\u00e9m disso, a taxa de compras recorrentes representa a fideliza\u00e7\u00e3o e a reten\u00e7\u00e3o dos clientes. Se estiver em baixa, est\u00e1 na hora de entender o que deve ser melhorado na sua loja virtual.&nbsp;<\/p>\n\n\n\n<p>Em resumo, o LTV ajuda na<strong> tomada de decis\u00f5es estrat\u00e9gicas<\/strong> para o seu neg\u00f3cio, com base em dados reais e direcionados ao seu p\u00fablico.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_se_considera_um_bom_lifetime_value_no_e-commerce\"><\/span>O que se considera um bom<em> lifetime value<\/em> no e-commerce?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>J\u00e1 sabemos qual \u00e9 a import\u00e2ncia do LTV, as m\u00e9tricas relevantes para a f\u00f3rmula e como fazer o c\u00e1lculo. Mas como interpretar se o resultado do LTV est\u00e1 bom ou ruim?<\/p>\n\n\n\n<p>A resposta para essa pergunta \u00e9: depende. N\u00e3o existe uma f\u00f3rmula geral para todos os segmentos de neg\u00f3cio, mas voc\u00ea pode considerar o seguinte: <strong>quanto maior o LTV, melhor para a sua loja<\/strong>.<\/p>\n\n\n\n<p>Em compara\u00e7\u00e3o com o CAC, o LTV precisa resultar em um valor superior ao que foi investido para adquirir esse cliente.&nbsp;<\/p>\n\n\n\n<p>Portanto, analisar o LTV considerando outras m\u00e9tricas, como o <strong>churn <\/strong>e o <strong>CAC<\/strong>, faz com que a <a href=\"https:\/\/www.yampi.com.br\/blog\/gestao-de-vendas\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\">gest\u00e3o do e-commerce<\/a> fique mais f\u00e1cil. Afinal, \u00e9 poss\u00edvel entender onde&nbsp; investir mais ou menos para captar e fidelizar clientes, determinar o <strong>mix de produtos<\/strong> da loja e a<strong> reposi\u00e7\u00e3o de estoque<\/strong> entre os que mais vendem ou geram lucro.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_aumentar_o_LTV_da_minha_loja_virtual\"><\/span>Como aumentar o LTV da minha loja virtual?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Mas ser\u00e1 que \u00e9 poss\u00edvel aumentar o LTV da sua loja virtual? <strong>Sim!<\/strong> Por isso, separamos aqui 7 estrat\u00e9gias para colocar em pr\u00e1tica e ver os seus resultados crescendo:&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Torne sua loja atrativa<\/h3>\n\n\n\n<p>Ter uma loja virtual bonita, com boas fotos, <a href=\"https:\/\/www.youtube.com\/watch?v=aQfKuS-c8pA\" target=\"_blank\" rel=\"noreferrer noopener\">descri\u00e7\u00e3o de produtos<\/a> e <a href=\"https:\/\/www.yampi.com.br\/blog\/o-que-e-checkout-transparente\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\">checkout transparente<\/a> atrai novos clientes e auxilia para que se tornem clientes recorrentes.<\/p>\n\n\n\n<p>Uma boa dica \u00e9 investir na cria\u00e7\u00e3o de um <a href=\"https:\/\/www.yampi.com.br\/blog\/branding-loja-virtual\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\"><em>branding<\/em><\/a><em> <\/em>\u00fanico e na identidade visual do seu neg\u00f3cio para manter a loja atrativa!&nbsp;<\/p>\n\n\n\n<p>\ud83c\udf93Saiba como criar um branding para a sua loja:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Yampi Academy - O que \u00e9 branding para loja virtual (Aula 1)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/WXO2cK99F3w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Atualize o mix de produtos<\/h3>\n\n\n\n<p>\u00c9 fundamental entender o que o seu p\u00fablico mais compra e o que traz mais retorno financeiro para manter o seu mix de produtos de acordo com o <strong>comportamento do consumidor<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fique de olho no estoque<\/h3>\n\n\n\n<p>Nada mais frustrante do que estar habituado a comprar de uma determinada loja e, em algum momento, se deparar com a<strong> falta de estoque<\/strong> do produto favorito.&nbsp;<\/p>\n\n\n\n<p>Por isso, mantenha seu <a href=\"https:\/\/www.yampi.com.br\/blog\/gestao-de-estoque\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\">estoque<\/a> em dia, entendendo quais s\u00e3o os tipos que melhor beneficiam o seu neg\u00f3cio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Invista em campanhas de m\u00eddia<\/h3>\n\n\n\n<p>Isso serve tanto para atrair novos clientes quanto para relembrar os clientes existentes de alguma promo\u00e7\u00e3o ou novos produtos que chegaram na sua loja.&nbsp;<\/p>\n\n\n\n<p>As <strong>campanhas de m\u00eddia <\/strong>s\u00e3o direcionadas e segmentadas, fazendo com que voc\u00ea atinja as pessoas certas para o seu neg\u00f3cio.<\/p>\n\n\n\n<p>\ud83c\udf93Vire expert em criar an\u00fancios para o seu e-commerce:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Yampi Academy - Google Ads para e-commerce (Aula 3)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/yYY5gJu1oeI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Aprimore o relacionamento com o cliente<\/h3>\n\n\n\n<p>Essa estrat\u00e9gia contribui muito para que o seu cliente tenha uma \u00f3tima experi\u00eancia de compra e recomende a loja para mais pessoas.&nbsp;<\/p>\n\n\n\n<p>O <a href=\"https:\/\/www.yampi.com.br\/blog\/relacionamento-com-o-cliente\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>relacionamento com o cliente<\/strong><\/a><strong> <\/strong>pode ser feito atrav\u00e9s de disparo de pesquisas p\u00f3s-compra e contato para coletar <em>feedbacks<\/em>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Disponibilize canais de atendimento<\/h3>\n\n\n\n<p>A transpar\u00eancia nas rela\u00e7\u00f5es faz toda a diferen\u00e7a no retorno do cliente. Portanto, tenha um espa\u00e7o no seu e-commerce com os <strong>canais de comunica\u00e7\u00e3o <\/strong>divulgados e claro,&nbsp; ofere\u00e7a o melhor <a href=\"https:\/\/www.yampi.com.br\/blog\/como-melhorar-atendimento-ecommerce\/?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv-lifetime-value\" target=\"_blank\" rel=\"noreferrer noopener\">atendimento<\/a> poss\u00edvel para solucionar as quest\u00f5es que possam surgir.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fa\u00e7a campanhas de reten\u00e7\u00e3o de clientes<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.yampi.com.br\/blog\/calendario-comercial\/#?utm_source=blog&amp;utm_medium=organico&amp;utm_campaign=&amp;utm_content=&amp;utm_term=ltv\" target=\"_blank\" rel=\"noreferrer noopener\">Datas comemorativas<\/a>, anivers\u00e1rio, anivers\u00e1rio de compra do cliente, descontos progressivos para <strong>compras recorrentes<\/strong>. Todas essas a\u00e7\u00f5es podem ser inclu\u00eddas em <strong>campanhas de reten\u00e7\u00e3o<\/strong>.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/www.youtube.com\/playlist?list=PLBYDJNQqmSHdfcfJ8gBlLBMkto844l1b1\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"245\" src=\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/Banner_167-1024x245.png\" alt=\"Bot\u00e3o para assistir Yampi Academy\" class=\"wp-image-1468\" style=\"width:840px;height:auto\" srcset=\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/Banner_167-1024x245.png 1024w, https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/Banner_167-300x72.png 300w, https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/Banner_167-768x184.png 768w, https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/Banner_167-1536x367.png 1536w, https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/Banner_167.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"198\" src=\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2025\/01\/Assinatura_Aurea.png\" alt=\"\" class=\"wp-image-3393\" srcset=\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2025\/01\/Assinatura_Aurea.png 1024w, https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2025\/01\/Assinatura_Aurea-300x58.png 300w, https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2025\/01\/Assinatura_Aurea-768x149.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O LTV \u00e9 um indicador essencial para qualquer e-commerce. Aprenda aqui como calcular e aumentar o lifetime value da sua loja virtual!<\/p>\n","protected":false},"author":20,"featured_media":3871,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[64,35,68,72],"tags":[29,23],"class_list":["post-1467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao","category-marketing-digital","category-negocios","category-vendas-online","tag-marketing-para-e-commerce","tag-vendas-online"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como aumentar o LTV do seu e-commerce | Blog da Yampi<\/title>\n<meta name=\"description\" content=\"O LTV \u00e9 um indicador essencial para qualquer e-commerce. Aprenda aqui como calcular e aumentar o lifetime value da sua loja virtual!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como aumentar o LTV do seu e-commerce | Blog da Yampi\" \/>\n<meta property=\"og:description\" content=\"O LTV \u00e9 um indicador essencial para qualquer e-commerce. Aprenda aqui como calcular e aumentar o lifetime value da sua loja virtual!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Yampi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/somosyampi\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T20:35:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T19:09:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Aurea Araujo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aurea Araujo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/\"},\"author\":{\"name\":\"Aurea Araujo\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#\/schema\/person\/5f5879d27ed49c754a35d2e02007b8a6\"},\"headline\":\"Como aumentar o LTV da sua loja virtual em 7 estrat\u00e9gias\",\"datePublished\":\"2023-07-20T20:35:58+00:00\",\"dateModified\":\"2025-08-11T19:09:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/\"},\"wordCount\":1548,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png\",\"keywords\":[\"Marketing para e-commerce\",\"Vendas online\"],\"articleSection\":[\"Gest\u00e3o\",\"Marketing digital\",\"Neg\u00f3cios\",\"Vendas online\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/\",\"url\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/\",\"name\":\"Como aumentar o LTV do seu e-commerce | Blog da Yampi\",\"isPartOf\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png\",\"datePublished\":\"2023-07-20T20:35:58+00:00\",\"dateModified\":\"2025-08-11T19:09:43+00:00\",\"description\":\"O LTV \u00e9 um indicador essencial para qualquer e-commerce. Aprenda aqui como calcular e aumentar o lifetime value da sua loja virtual!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#primaryimage\",\"url\":\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png\",\"contentUrl\":\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png\",\"width\":920,\"height\":480,\"caption\":\"Life time Value\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.yampi.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gest\u00e3o\",\"item\":\"https:\/\/www.yampi.com.br\/blog\/category\/gestao\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.yampi.com.br\/blog\/category\/gestao\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Como aumentar o LTV da sua loja virtual em 7 estrat\u00e9gias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#website\",\"url\":\"https:\/\/www.yampi.com.br\/blog\/\",\"name\":\"Blog da Yampi\",\"description\":\"Conte\u00fado sobre e-commerce\",\"publisher\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.yampi.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#organization\",\"name\":\"Yampi\",\"url\":\"https:\/\/www.yampi.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2022\/06\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2022\/06\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Yampi\"},\"image\":{\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/somosyampi\",\"https:\/\/www.instagram.com\/somosyampi\",\"https:\/\/www.linkedin.com\/company\/somosyampi\",\"https:\/\/www.youtube.com\/channel\/UCDfDYNkud7PL9N2TDnD4Mtg\",\"https:\/\/yampi.gupy.io\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#\/schema\/person\/5f5879d27ed49c754a35d2e02007b8a6\",\"name\":\"Aurea Araujo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.yampi.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2024\/01\/image-45-96x96.jpg\",\"contentUrl\":\"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2024\/01\/image-45-96x96.jpg\",\"caption\":\"Aurea Araujo\"},\"url\":\"https:\/\/www.yampi.com.br\/blog\/author\/aurea-araujo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como aumentar o LTV do seu e-commerce | Blog da Yampi","description":"O LTV \u00e9 um indicador essencial para qualquer e-commerce. Aprenda aqui como calcular e aumentar o lifetime value da sua loja virtual!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/","og_locale":"pt_BR","og_type":"article","og_title":"Como aumentar o LTV do seu e-commerce | Blog da Yampi","og_description":"O LTV \u00e9 um indicador essencial para qualquer e-commerce. Aprenda aqui como calcular e aumentar o lifetime value da sua loja virtual!","og_url":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/","og_site_name":"Blog da Yampi","article_publisher":"https:\/\/www.facebook.com\/somosyampi","article_published_time":"2023-07-20T20:35:58+00:00","article_modified_time":"2025-08-11T19:09:43+00:00","og_image":[{"width":920,"height":480,"url":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png","type":"image\/png"}],"author":"Aurea Araujo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Aurea Araujo","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#article","isPartOf":{"@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/"},"author":{"name":"Aurea Araujo","@id":"https:\/\/www.yampi.com.br\/blog\/#\/schema\/person\/5f5879d27ed49c754a35d2e02007b8a6"},"headline":"Como aumentar o LTV da sua loja virtual em 7 estrat\u00e9gias","datePublished":"2023-07-20T20:35:58+00:00","dateModified":"2025-08-11T19:09:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/"},"wordCount":1548,"commentCount":0,"publisher":{"@id":"https:\/\/www.yampi.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png","keywords":["Marketing para e-commerce","Vendas online"],"articleSection":["Gest\u00e3o","Marketing digital","Neg\u00f3cios","Vendas online"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/","url":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/","name":"Como aumentar o LTV do seu e-commerce | Blog da Yampi","isPartOf":{"@id":"https:\/\/www.yampi.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#primaryimage"},"image":{"@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png","datePublished":"2023-07-20T20:35:58+00:00","dateModified":"2025-08-11T19:09:43+00:00","description":"O LTV \u00e9 um indicador essencial para qualquer e-commerce. Aprenda aqui como calcular e aumentar o lifetime value da sua loja virtual!","breadcrumb":{"@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#primaryimage","url":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png","contentUrl":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2023\/07\/LTV-Lifetime-Value.png","width":920,"height":480,"caption":"Life time Value"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yampi.com.br\/blog\/ltv-lifetime-value\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.yampi.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gest\u00e3o","item":"https:\/\/www.yampi.com.br\/blog\/category\/gestao\/"},{"@type":"ListItem","position":3,"name":"Neg\u00f3cios","item":"https:\/\/www.yampi.com.br\/blog\/category\/gestao\/negocios\/"},{"@type":"ListItem","position":4,"name":"Como aumentar o LTV da sua loja virtual em 7 estrat\u00e9gias"}]},{"@type":"WebSite","@id":"https:\/\/www.yampi.com.br\/blog\/#website","url":"https:\/\/www.yampi.com.br\/blog\/","name":"Blog da Yampi","description":"Conte\u00fado sobre e-commerce","publisher":{"@id":"https:\/\/www.yampi.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yampi.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.yampi.com.br\/blog\/#organization","name":"Yampi","url":"https:\/\/www.yampi.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.yampi.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2022\/06\/cropped-favicon.png","contentUrl":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2022\/06\/cropped-favicon.png","width":512,"height":512,"caption":"Yampi"},"image":{"@id":"https:\/\/www.yampi.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/somosyampi","https:\/\/www.instagram.com\/somosyampi","https:\/\/www.linkedin.com\/company\/somosyampi","https:\/\/www.youtube.com\/channel\/UCDfDYNkud7PL9N2TDnD4Mtg","https:\/\/yampi.gupy.io\/"]},{"@type":"Person","@id":"https:\/\/www.yampi.com.br\/blog\/#\/schema\/person\/5f5879d27ed49c754a35d2e02007b8a6","name":"Aurea Araujo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.yampi.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2024\/01\/image-45-96x96.jpg","contentUrl":"https:\/\/www.yampi.com.br\/blog\/wp-content\/uploads\/2024\/01\/image-45-96x96.jpg","caption":"Aurea Araujo"},"url":"https:\/\/www.yampi.com.br\/blog\/author\/aurea-araujo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/posts\/1467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1467"}],"version-history":[{"count":5,"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/posts\/1467\/revisions"}],"predecessor-version":[{"id":3596,"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/posts\/1467\/revisions\/3596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/media\/3871"}],"wp:attachment":[{"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yampi.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}